{"id":80948,"date":"2013-10-15T12:00:30","date_gmt":"2013-10-15T10:00:30","guid":{"rendered":"https:\/\/newsroom.haitian.com\/alle\/rueckverlagerung-der-produktion-ins-heimische-schweden\/"},"modified":"2024-11-30T00:03:32","modified_gmt":"2024-11-29T23:03:32","slug":"rueckverlagerung-der-produktion-ins-heimische-schweden","status":"publish","type":"post","link":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/","title":{"rendered":"R\u00fcckverlagerung der Produktion ins heimische Schweden"},"content":{"rendered":"<div class=\"description\"><strong>Rennrodel, Snowboards, Kinderschlitten\u2026 Das schwedische Unter-nehmen STIGA Sports z\u00e4hlt weltweit zu den Top-Anbietern von Frei-zeit- und Wintersportartikeln. Die Kunststoffschlitten hatte STIGA Sports bislang in China fertigen lassen. Um die Produktion effizienter zu gestalten, wurde der gesamte Fertigungsprozess neu projektiert \u2013 und zur\u00fcckgeholt.<\/strong><\/div>\n<div class=\"content\">\n<p>Bislang hatte STIGA Sports die robusten Kinderschlitten in Fernost fertigen lassen. Seit Sommer 2013 jedoch erfolgt die Produktion der bunten \u201eClassic Sleds\u201c f\u00fcr Kinder wieder in Schweden. Den Weg zur\u00fcck ebnete ein Joint Venture mit dem benachbarten Kunststoffverarbeiter Memo \u2028Industriplast AB. Gemeinsam investierten STIGA und Memo Industriplast rund 10 Millionen Schwedische Kronen in eine komplett neue Fertigungslinie vor Ort. Hoch automatisiert \u2212 und damit konkurrenzf\u00e4hig zu Her-stellern in Fernost. Kern der hoch effizienten Anlage ist eine Haitian Mars \u2028Serie mit 14.000 kN Schlie\u00dfkraft, eingebunden in eine Fertigungszelle mit IML.<\/p>\n<p><strong>Ein Schritt zur\u00fcck, zwei Spr\u00fcnge nach vorn<\/strong><\/p>\n<p>Die Kooperation mit Memo Industriplast (und damit die R\u00fcckverlagerung der Produktion ins heimische Schweden) war mehr als ein logischer Schritt. Nicht nur, dass sich eines der Memo-Werke direkt neben dem Gel\u00e4nde von STIGA Sports befindet. Memo Industriplast z\u00e4hlt selbst zu den renommierten Unternehmen seiner Branche. Rund 50 Spritzgie\u00dfmaschinen verschiedener Fabrikate verarbeiten dort unterschiedlichste Rohstoffe wie PP, PE, PA, PC, TPE, ABS und magnetische Materialien. Das Produktionsspektrum umfasst neben Kunststoffmagneten und technischen Kunststoff- oder Hybridteilen f\u00fcr Automobile, Smartphones, medizinische Artikel, Heizungs- und L\u00fcftungssysteme auch Freizeitartikel und Sport-accessoires. Nun produziert M. I. auch den Schlitten f\u00fcr STIGA. \u201eDie unmittelbare Standortn\u00e4he ist nicht nur in der Logistik vorteilhaft. Vor allem wenn man so eng zusammen arbeitet wie wir, sind kurze Wege bei technischen Diskussionen ein klares Plus\u201c erl\u00e4utert Conny Tapper, Fertigungsleiter von Memo Industriplast. F\u00fcr Mats Bandstigen, CEO von STIGA Sports, hat sich parallel zur Handlungsf\u00e4higkeit seines Unternehmens auch die Kostenseite stark verbessert: \u201eDie Produktion in China hatte zwar wirtschaftliche Vorteile, aber auch lange Vorlaufzeiten. Durch die Nachbarschaft zu M. I. k\u00f6nnen wir nun schneller agieren und Neues entwickeln, mit der neuen Mars Serie aber auch schneller und viel effizienter produzieren. Das Preis-Leistungs-Verh\u00e4ltnis der Mars ist schlichtweg optimal, ja man kann sagen: Die gesamte Anlage arbeitet \u00fcberaus effizient.\u201c<\/p>\n<p><strong>Zw\u00f6lf Stunden mannlose Fertigung<\/strong><\/p>\n<p>Die Technologien und das Know-how der neuen Schlittenfertigung stammen ebenfalls aus Schweden, von der Haitian Vertretung Plamako. \u2028Christer Stureson, gesch\u00e4ftsf\u00fchrender Teilhaber von Plamako, kann die Testphase und die ausschlaggebenden Argumente noch gut erinnern: \u201eNiedrige Energiewerte, stabile Produktionsparameter und ein attraktiver Preis, damit konnte die Mars Serie am meisten punkten\u201c. Das Unternehmen, welches in Schweden auch die Generalvertretung von Sepro Robots inne hat, lieferte nicht nur die Mars, sondern integrierte sie auch in eine eigens projektierte, vollst\u00e4ndig automatisierte Fertigungszelle. \u201eIm Prinzip wird das Produkt kein einziges Mal von einer menschlichen Hand ber\u00fchrt \u2013 bis zum Lager von STIGA Sports\u201c so Christer Stureson.<\/p>\n<p>Der mit 14.000 kN in der Mars entstandene Schlitten wird vom Greifer-system eines 5-Achs-Roboters aufgenommen und zur Stapelstation gef\u00fchrt. Unterwegs wird noch \u201eon the fly\u201c ein Reflektions-Sticker angebracht, der zuvor elektrisch aufgeladen wurde. Von der Stapelstation \u2013 sie bietet Platz f\u00fcr 12 Europaletten \u2013 transportiert ein F\u00f6rderband die Schlitten direkt ins Warenlager. Die komplette Anlage ist f\u00fcr 12 Stunden mannlose Fertigung ausgelegt und kann mehr als 800 Tonnen Rohstoff j\u00e4hrlich verarbeiten. Das Produktionsvolumen betr\u00e4gt ca. 300.000 Schlitten pro Jahr.<\/p>\n<p><strong>Wirtschaftlichkeit ist Programm<\/strong><\/p>\n<p>Seit ihrer Einf\u00fchrung vor 7 Jahren wurde die Mars Serie \u00fcber 90.000 verkauft \u2013 h\u00f6chst wahrscheinlich die bislang erfolgreichste Maschinenserie in der Geschichte der Kunststoffspritzgie\u00dfmaschinen. Die innovative servo-hydraulische Mars-Antriebstechnologie erh\u00f6ht die Produktionseffizienz und sorgt f\u00fcr geringsten Energieverbrauch. Auf der K-Messe wird eine die Economy-Variante der Mars II Serie mit 1.200 kN Schlie\u00dfkraft gezeigt. Sie produziert einen Koffer mit 135 g Gewicht aus PP transparent. Ausgestattet mit einem 4-zonen Hei\u00dfkanalsystem und einem Robot-System der Firma Sepro. Der Energieverbrauch dieser Anwendung liegt bei 8,3 kW\/h.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rennrodel, Snowboards, Kinderschlitten\u2026 Das schwedische Unter-nehmen STIGA Sports z\u00e4hlt weltweit zu den Top-Anbietern von Frei-zeit- und Wintersportartikeln. Die Kunststoffschlitten hatte STIGA Sports bislang in China fertigen lassen. Um die Produktion effizienter zu gestalten, wurde der gesamte Fertigungsprozess neu projektiert \u2013 und zur\u00fcckgeholt. Bislang hatte STIGA Sports die robusten Kinderschlitten in Fernost fertigen lassen. Seit Sommer [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5,292,270],"tags":[],"class_list":["post-80948","post","type-post","status-publish","format-standard","hentry","category-all-de","category-haitian-international-news-de","category-company-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckverlagerung der Produktion ins heimische Schweden - Haitian Newsroom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckverlagerung der Produktion ins heimische Schweden - Haitian Newsroom\" \/>\n<meta property=\"og:description\" content=\"Rennrodel, Snowboards, Kinderschlitten\u2026 Das schwedische Unter-nehmen STIGA Sports z\u00e4hlt weltweit zu den Top-Anbietern von Frei-zeit- und Wintersportartikeln. Die Kunststoffschlitten hatte STIGA Sports bislang in China fertigen lassen. Um die Produktion effizienter zu gestalten, wurde der gesamte Fertigungsprozess neu projektiert \u2013 und zur\u00fcckgeholt. Bislang hatte STIGA Sports die robusten Kinderschlitten in Fernost fertigen lassen. Seit Sommer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/\" \/>\n<meta property=\"og:site_name\" content=\"Haitian Newsroom\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/haitiangermany\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-15T10:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T23:03:32+00:00\" \/>\n<meta name=\"author\" content=\"haitianwiesnerd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"haitianwiesnerd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/\"},\"author\":{\"name\":\"haitianwiesnerd\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#\\\/schema\\\/person\\\/6aee888a065f2f55aef76248e9d276ea\"},\"headline\":\"R\u00fcckverlagerung der Produktion ins heimische Schweden\",\"datePublished\":\"2013-10-15T10:00:30+00:00\",\"dateModified\":\"2024-11-29T23:03:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/\"},\"wordCount\":640,\"publisher\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#organization\"},\"articleSection\":[\"Alle\",\"Haitian International\",\"Unternehmen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/\",\"url\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/\",\"name\":\"R\u00fcckverlagerung der Produktion ins heimische Schweden - Haitian Newsroom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#website\"},\"datePublished\":\"2013-10-15T10:00:30+00:00\",\"dateModified\":\"2024-11-29T23:03:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/all-de\\\/rueckverlagerung-der-produktion-ins-heimische-schweden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/news-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Haitian International\",\"item\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/news-de\\\/haitian-international-news-de\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"R\u00fcckverlagerung der Produktion ins heimische Schweden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/\",\"name\":\"Haitian Newsroom\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#organization\",\"name\":\"Haitian International Germany GmbH\",\"url\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newsroom.haitian.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/HTI.svg\",\"contentUrl\":\"https:\\\/\\\/newsroom.haitian.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/HTI.svg\",\"width\":1,\"height\":1,\"caption\":\"Haitian International Germany GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/haitiangermany\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/haitian-international-germany\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/HaitianInternationalGermany\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/#\\\/schema\\\/person\\\/6aee888a065f2f55aef76248e9d276ea\",\"name\":\"haitianwiesnerd\",\"url\":\"https:\\\/\\\/newsroom.haitian.com\\\/de\\\/author\\\/haitianwiesnerd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckverlagerung der Produktion ins heimische Schweden - Haitian Newsroom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckverlagerung der Produktion ins heimische Schweden - Haitian Newsroom","og_description":"Rennrodel, Snowboards, Kinderschlitten\u2026 Das schwedische Unter-nehmen STIGA Sports z\u00e4hlt weltweit zu den Top-Anbietern von Frei-zeit- und Wintersportartikeln. Die Kunststoffschlitten hatte STIGA Sports bislang in China fertigen lassen. Um die Produktion effizienter zu gestalten, wurde der gesamte Fertigungsprozess neu projektiert \u2013 und zur\u00fcckgeholt. Bislang hatte STIGA Sports die robusten Kinderschlitten in Fernost fertigen lassen. Seit Sommer [&hellip;]","og_url":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/","og_site_name":"Haitian Newsroom","article_publisher":"https:\/\/www.facebook.com\/haitiangermany","article_published_time":"2013-10-15T10:00:30+00:00","article_modified_time":"2024-11-29T23:03:32+00:00","author":"haitianwiesnerd","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"haitianwiesnerd","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/#article","isPartOf":{"@id":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/"},"author":{"name":"haitianwiesnerd","@id":"https:\/\/newsroom.haitian.com\/de\/#\/schema\/person\/6aee888a065f2f55aef76248e9d276ea"},"headline":"R\u00fcckverlagerung der Produktion ins heimische Schweden","datePublished":"2013-10-15T10:00:30+00:00","dateModified":"2024-11-29T23:03:32+00:00","mainEntityOfPage":{"@id":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/"},"wordCount":640,"publisher":{"@id":"https:\/\/newsroom.haitian.com\/de\/#organization"},"articleSection":["Alle","Haitian International","Unternehmen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/","url":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/","name":"R\u00fcckverlagerung der Produktion ins heimische Schweden - Haitian Newsroom","isPartOf":{"@id":"https:\/\/newsroom.haitian.com\/de\/#website"},"datePublished":"2013-10-15T10:00:30+00:00","dateModified":"2024-11-29T23:03:32+00:00","breadcrumb":{"@id":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsroom.haitian.com\/de\/all-de\/rueckverlagerung-der-produktion-ins-heimische-schweden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsroom.haitian.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/newsroom.haitian.com\/de\/news-de\/"},{"@type":"ListItem","position":3,"name":"Haitian International","item":"https:\/\/newsroom.haitian.com\/de\/news-de\/haitian-international-news-de\/"},{"@type":"ListItem","position":4,"name":"R\u00fcckverlagerung der Produktion ins heimische Schweden"}]},{"@type":"WebSite","@id":"https:\/\/newsroom.haitian.com\/de\/#website","url":"https:\/\/newsroom.haitian.com\/de\/","name":"Haitian Newsroom","description":"","publisher":{"@id":"https:\/\/newsroom.haitian.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsroom.haitian.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/newsroom.haitian.com\/de\/#organization","name":"Haitian International Germany GmbH","url":"https:\/\/newsroom.haitian.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/newsroom.haitian.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/newsroom.haitian.com\/wp-content\/uploads\/sites\/4\/2023\/12\/HTI.svg","contentUrl":"https:\/\/newsroom.haitian.com\/wp-content\/uploads\/sites\/4\/2023\/12\/HTI.svg","width":1,"height":1,"caption":"Haitian International Germany GmbH"},"image":{"@id":"https:\/\/newsroom.haitian.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/haitiangermany","https:\/\/www.linkedin.com\/company\/haitian-international-germany\/","https:\/\/www.youtube.com\/c\/HaitianInternationalGermany"]},{"@type":"Person","@id":"https:\/\/newsroom.haitian.com\/de\/#\/schema\/person\/6aee888a065f2f55aef76248e9d276ea","name":"haitianwiesnerd","url":"https:\/\/newsroom.haitian.com\/de\/author\/haitianwiesnerd\/"}]}},"_links":{"self":[{"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/posts\/80948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/comments?post=80948"}],"version-history":[{"count":1,"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/posts\/80948\/revisions"}],"predecessor-version":[{"id":88062,"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/posts\/80948\/revisions\/88062"}],"wp:attachment":[{"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/media?parent=80948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/categories?post=80948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsroom.haitian.com\/de\/wp-json\/wp\/v2\/tags?post=80948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}